{"id":110666,"date":"2024-09-27T12:34:10","date_gmt":"2024-09-27T12:34:10","guid":{"rendered":"https:\/\/emailchef.com\/?page_id=110666"},"modified":"2026-08-21T07:31:59","modified_gmt":"2026-08-21T07:31:59","slug":"evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation","status":"publish","type":"page","link":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/","title":{"rendered":"\u00c9v\u00e9nements dans les Flows : comment ils fonctionnent dans l&#8217;email marketing automation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"110666\" class=\"elementor elementor-110666 elementor-75222\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d100b30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d100b30\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8eb00d3\" data-id=\"8eb00d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e754a17 elementor-widget elementor-widget-text-editor\" data-id=\"e754a17\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Los eventos son los elementos que te permiten <strong>monitorizar y reaccionar ante acciones o comportamientos espec&iacute;ficos<\/strong> de tus contactos dentro de un Flow. A diferencia de los puntos de entrada, que inician la automatizaci&oacute;n, los eventos pausan el Flow y esperan que se produzca una acci&oacute;n determinada dentro de un intervalo de tiempo que defines t&uacute;.<\/p>\n<p>Si el evento se produce dentro del tiempo indicado, el Flow contin&uacute;a por la rama <em>S&iacute;<\/em>. Si no se produce antes del plazo, el Flow contin&uacute;a autom&aacute;ticamente por la rama <em>No<\/em>.<\/p>\n<p>A continuaci&oacute;n encontrar&aacute;s todos los eventos disponibles en Emailchef, con una descripci&oacute;n de c&oacute;mo funciona cada uno.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19a420e elementor-widget elementor-widget-image\" data-id=\"19a420e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"358\" height=\"607\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2026\/08\/evenements-dans-les-flows.jpg\" class=\"attachment-large size-large wp-image-110668\" alt=\"\u00c9v\u00e9nements dans les Flows : comment ils fonctionnent dans l&#039;email marketing automation\" srcset=\"https:\/\/emailchef.com\/wp-content\/uploads\/2026\/08\/evenements-dans-les-flows.jpg 358w, https:\/\/emailchef.com\/wp-content\/uploads\/2026\/08\/evenements-dans-les-flows-177x300.jpg 177w\" sizes=\"(max-width: 358px) 100vw, 358px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-053649f elementor-widget elementor-widget-text-editor\" data-id=\"053649f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Message Ouvert ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-message-ouvert-comment-le-configurer-dans-un-flow\/\">Message Ouvert ?<\/a><\/strong> Attend que le contact ouvre un email sp\u00e9cifique. Il est utile pour \u00e9valuer le niveau d&#8217;int\u00e9r\u00eat pour une communication : si ouvert, le Flow continue par la branche Oui et vous pouvez envoyer une offre suppl\u00e9mentaire cibl\u00e9e ; si non ouvert dans le d\u00e9lai imparti, il continue par la branche Non.<\/li><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Message Cliqu\u00e9 ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-message-clique-comment-le-configurer-dans-un-flow\/\">Message Cliqu\u00e9 ?<\/a><\/strong> Un clic sur un lien dans un email sp\u00e9cifique fait avancer le Flow par la branche Oui. Il est id\u00e9al pour surveiller l&#8217;int\u00e9r\u00eat pour certains contenus : par exemple, vous pouvez attendre le clic sur un lien d&#8217;inscription \u00e0 un webinaire et, si cliqu\u00e9, envoyer automatiquement les d\u00e9tails de l&#8217;\u00e9v\u00e9nement.<\/li><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Message livr\u00e9 ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-message-livre-comment-le-configurer-dans-un-flow\/\">Message livr\u00e9 ?<\/a><\/strong> V\u00e9rifie qu&#8217;un email sp\u00e9cifique a \u00e9t\u00e9 livr\u00e9 avec succ\u00e8s dans la bo\u00eete de r\u00e9ception du contact avant que le Flow ne continue. Il est utile pour garantir que les communications suivantes ne se d\u00e9clenchent qu&#8217;apr\u00e8s une livraison confirm\u00e9e : par exemple, vous pouvez attendre que l&#8217;email d&#8217;onboarding soit livr\u00e9 avant d&#8217;envoyer un sondage ou un suivi.<\/li><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Formulaire soumis ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-formulaire-soumis-comment-le-configurer-dans-un-flow\/\">Formulaire soumis ?<\/a><\/strong> La soumission d&#8217;un formulaire par le contact fait avancer le Flow par la branche Oui. Il est utile pour intercepter le moment exact o\u00f9 un contact effectue une action concr\u00e8te : par exemple, vous pouvez attendre l&#8217;envoi d&#8217;un formulaire de demande d&#8217;informations et, s&#8217;il est soumis, d\u00e9clencher automatiquement une s\u00e9quence de suivi d\u00e9di\u00e9e.<\/li><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Valeur du Champ d'un Contact ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-valeur-du-champ-dun-contact-comment-le-configurer-dans-un-flow\/\">Valeur du Champ d&#8217;un Contact ?<\/a><\/strong> Lorsqu&#8217;un champ du profil du contact prend une valeur sp\u00e9cifique, le Flow avance par la branche Oui. Il est parfait pour personnaliser les parcours d&#8217;automatisation en fonction des changements dans les donn\u00e9es de vos contacts : par exemple, vous pouvez attendre que le champ &#8220;Statut&#8221; passe \u00e0 &#8220;Client&#8221; et, quand cela se produit, envoyer un email de bienvenue personnalis\u00e9.<\/li><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Le contact entre dans un segment ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-le-contact-entre-dans-un-segment-comment-le-configurer-dans-un-flow\/\">Le contact entre dans un segment ?<\/a><\/strong> D\u00e8s que le contact rejoint un segment sp\u00e9cifique, le Flow d\u00e9verrouille la branche Oui. Il est utile pour suivre dynamiquement les groupes auxquels appartiennent vos abonn\u00e9s : par exemple, vous pouvez attendre qu&#8217;un contact entre dans le segment &#8220;Clients VIP&#8221; et, si cela se produit, d\u00e9clencher automatiquement un Flow de communications exclusives.<\/li><li style=\"margin-bottom: 15px;\"><strong><a title=\"\u00c9v\u00e9nement : Le contact s'abonne ?\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenement-le-contact-sabonne-comment-le-configurer-dans-un-flow\/\">Le contact s&#8217;abonne ?<\/a><\/strong> L&#8217;inscription du contact \u00e0 une liste sp\u00e9cifique fait avancer le Flow par la branche Oui. Il est particuli\u00e8rement utile pour g\u00e9rer des inscriptions parall\u00e8les \u00e0 diff\u00e9rentes listes : par exemple, vous pouvez attendre l&#8217;inscription \u00e0 votre newsletter et, quand elle se produit, lancer automatiquement une s\u00e9quence d&#8217;emails de bienvenue.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Los eventos son los elementos que te permiten monitorizar y reaccionar ante acciones o comportamientos espec&iacute;ficos de tus contactos dentro de un Flow. A diferencia de los puntos de entrada, que inician la automatizaci&oacute;n, los eventos pausan el Flow y esperan que se produzca una acci&oacute;n determinada dentro de un intervalo de tiempo que defines [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1193,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-110666","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9v\u00e9nements dans les Flows d&#039;email marketing automation<\/title>\n<meta name=\"description\" content=\"Les \u00c9v\u00e9nements dans les Flows Emailchef mettent en pause l&#039;automatisation et attendent une action du contact pour continuer par la branche Oui ou Non\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9v\u00e9nements dans les Flows d'email marketing automation","description":"Les \u00c9v\u00e9nements dans les Flows Emailchef mettent en pause l'automatisation et attendent une action du contact pour continuer par la branche Oui ou Non","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/","url":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/","name":"\u00c9v\u00e9nements dans les Flows d'email marketing automation","isPartOf":{"@id":"https:\/\/emailchef.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/#primaryimage"},"image":{"@id":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/#primaryimage"},"thumbnailUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2026\/08\/evenements-dans-les-flows.jpg","datePublished":"2024-09-27T12:34:10+00:00","dateModified":"2026-08-21T07:31:59+00:00","description":"Les \u00c9v\u00e9nements dans les Flows Emailchef mettent en pause l'automatisation et attendent une action du contact pour continuer par la branche Oui ou Non","breadcrumb":{"@id":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/#primaryimage","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2026\/08\/evenements-dans-les-flows.jpg","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2026\/08\/evenements-dans-les-flows.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/evenements-dans-les-flows-comment-ils-fonctionnent-dans-lemail-marketing-automation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/emailchef.com\/fr\/mailchef-email-marketing-emailing-et-envoi-newsletter\/"},{"@type":"ListItem","position":2,"name":"Base de connaissance","item":"https:\/\/emailchef.com\/fr\/base-de-connaissance\/"},{"@type":"ListItem","position":3,"name":"\u00c9v\u00e9nements dans les Flows : comment ils fonctionnent dans l&#8217;email marketing automation"}]},{"@type":"WebSite","@id":"https:\/\/emailchef.com\/fr\/#website","url":"https:\/\/emailchef.com\/fr\/","name":"Emailchef","description":"Recettes go\u00fbteuses pour vos emails","publisher":{"@id":"https:\/\/emailchef.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emailchef.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/emailchef.com\/fr\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/emailchef.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emailchef.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/emailchef.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/pages\/110666"}],"collection":[{"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/comments?post=110666"}],"version-history":[{"count":10,"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/pages\/110666\/revisions"}],"predecessor-version":[{"id":111760,"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/pages\/110666\/revisions\/111760"}],"up":[{"embeddable":true,"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/pages\/1193"}],"wp:attachment":[{"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/media?parent=110666"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/emailchef.com\/fr\/wp-json\/wp\/v2\/g1_relation_tag?post=110666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}